{"id":7102,"date":"2017-11-26T12:48:29","date_gmt":"2017-11-26T10:48:29","guid":{"rendered":"http:\/\/www.ukr-ayna.com\/wp-content\/uploads\/2017\/11\/golodomor_samsun2.jpg"},"modified":"2017-11-26T12:49:04","modified_gmt":"2017-11-26T10:49:04","slug":"golodomor_samsun2","status":"inherit","type":"attachment","link":"https:\/\/www.ukr-ayna.com\/uk\/golodomor-borotba-trivaie\/golodomor_samsun2\/","title":{"rendered":"\u0412\u0448\u0430\u043d\u0443\u0432\u0430\u043d\u043d\u044f \u043f\u0430\u043c&#8217;\u044f\u0442\u0456 \u0436\u0435\u0440\u0442\u0432 \u0413\u043e\u043b\u043e\u0434\u043e\u043c\u043e\u0440\u0443 \u0432 \u0421\u0430\u043c\u0441\u0443\u043d\u0456"},"author":16,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-7102","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.ukr-ayna.com\/wp-content\/uploads\/2017\/11\/golodomor_samsun2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"258\" src=\"https:\/\/www.ukr-ayna.com\/wp-content\/uploads\/2017\/11\/golodomor_samsun2-300x258.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.ukr-ayna.com\/wp-content\/uploads\/2017\/11\/golodomor_samsun2-300x258.jpg 300w, https:\/\/www.ukr-ayna.com\/wp-content\/uploads\/2017\/11\/golodomor_samsun2-768x660.jpg 768w, https:\/\/www.ukr-ayna.com\/wp-content\/uploads\/2017\/11\/golodomor_samsun2-696x598.jpg 696w, https:\/\/www.ukr-ayna.com\/wp-content\/uploads\/2017\/11\/golodomor_samsun2-489x420.jpg 489w, https:\/\/www.ukr-ayna.com\/wp-content\/uploads\/2017\/11\/golodomor_samsun2-800x688.jpg 800w, https:\/\/www.ukr-ayna.com\/wp-content\/uploads\/2017\/11\/golodomor_samsun2.jpg 960w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-wp-pid=\"7102\" nopin=\"nopin\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":960,"height":825,"file":"2017\/11\/golodomor_samsun2.jpg","sizes":{"thumbnail":{"file":"golodomor_samsun2-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ukr-ayna.com\/wp-content\/uploads\/2017\/11\/golodomor_samsun2-150x150.jpg"},"medium":{"file":"golodomor_samsun2-300x258.jpg","width":300,"height":258,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ukr-ayna.com\/wp-content\/uploads\/2017\/11\/golodomor_samsun2-300x258.jpg"},"medium_large":{"file":"golodomor_samsun2-768x660.jpg","width":768,"height":660,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ukr-ayna.com\/wp-content\/uploads\/2017\/11\/golodomor_samsun2-768x660.jpg"},"td_80x60":{"file":"golodomor_samsun2-80x60.jpg","width":80,"height":60,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ukr-ayna.com\/wp-content\/uploads\/2017\/11\/golodomor_samsun2-80x60.jpg"},"td_100x70":{"file":"golodomor_samsun2-100x70.jpg","width":100,"height":70,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ukr-ayna.com\/wp-content\/uploads\/2017\/11\/golodomor_samsun2-100x70.jpg"},"td_218x150":{"file":"golodomor_samsun2-218x150.jpg","width":218,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ukr-ayna.com\/wp-content\/uploads\/2017\/11\/golodomor_samsun2-218x150.jpg"},"td_265x198":{"file":"golodomor_samsun2-265x198.jpg","width":265,"height":198,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ukr-ayna.com\/wp-content\/uploads\/2017\/11\/golodomor_samsun2-265x198.jpg"},"td_324x160":{"file":"golodomor_samsun2-324x160.jpg","width":324,"height":160,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ukr-ayna.com\/wp-content\/uploads\/2017\/11\/golodomor_samsun2-324x160.jpg"},"td_324x235":{"file":"golodomor_samsun2-324x235.jpg","width":324,"height":235,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ukr-ayna.com\/wp-content\/uploads\/2017\/11\/golodomor_samsun2-324x235.jpg"},"td_324x400":{"file":"golodomor_samsun2-324x400.jpg","width":324,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ukr-ayna.com\/wp-content\/uploads\/2017\/11\/golodomor_samsun2-324x400.jpg"},"td_356x220":{"file":"golodomor_samsun2-356x220.jpg","width":356,"height":220,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ukr-ayna.com\/wp-content\/uploads\/2017\/11\/golodomor_samsun2-356x220.jpg"},"td_356x364":{"file":"golodomor_samsun2-356x364.jpg","width":356,"height":364,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ukr-ayna.com\/wp-content\/uploads\/2017\/11\/golodomor_samsun2-356x364.jpg"},"td_533x261":{"file":"golodomor_samsun2-533x261.jpg","width":533,"height":261,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ukr-ayna.com\/wp-content\/uploads\/2017\/11\/golodomor_samsun2-533x261.jpg"},"td_534x462":{"file":"golodomor_samsun2-534x462.jpg","width":534,"height":462,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ukr-ayna.com\/wp-content\/uploads\/2017\/11\/golodomor_samsun2-534x462.jpg"},"td_696x0":{"file":"golodomor_samsun2-696x598.jpg","width":696,"height":598,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ukr-ayna.com\/wp-content\/uploads\/2017\/11\/golodomor_samsun2-696x598.jpg"},"td_696x385":{"file":"golodomor_samsun2-696x385.jpg","width":696,"height":385,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ukr-ayna.com\/wp-content\/uploads\/2017\/11\/golodomor_samsun2-696x385.jpg"},"td_741x486":{"file":"golodomor_samsun2-741x486.jpg","width":741,"height":486,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ukr-ayna.com\/wp-content\/uploads\/2017\/11\/golodomor_samsun2-741x486.jpg"},"td_1068x580":{"file":"golodomor_samsun2-960x580.jpg","width":960,"height":580,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ukr-ayna.com\/wp-content\/uploads\/2017\/11\/golodomor_samsun2-960x580.jpg"},"td_0x420":{"file":"golodomor_samsun2-489x420.jpg","width":489,"height":420,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ukr-ayna.com\/wp-content\/uploads\/2017\/11\/golodomor_samsun2-489x420.jpg"},"wpsso-schema":{"file":"golodomor_samsun2-800x688.jpg","width":800,"height":688,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ukr-ayna.com\/wp-content\/uploads\/2017\/11\/golodomor_samsun2-800x688.jpg"},"wpsso-schema-article":{"file":"golodomor_samsun2-800x688.jpg","width":800,"height":688,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ukr-ayna.com\/wp-content\/uploads\/2017\/11\/golodomor_samsun2-800x688.jpg"},"wpsso-opengraph":{"file":"golodomor_samsun2-600x315-cropped.jpg","width":600,"height":315,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ukr-ayna.com\/wp-content\/uploads\/2017\/11\/golodomor_samsun2-600x315-cropped.jpg"},"wpsso-tc-summary":{"file":"golodomor_samsun2-600x600.jpg","width":600,"height":600,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ukr-ayna.com\/wp-content\/uploads\/2017\/11\/golodomor_samsun2-600x600.jpg"},"wpsso-tc-lrgimg":{"file":"golodomor_samsun2-800x688.jpg","width":800,"height":688,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ukr-ayna.com\/wp-content\/uploads\/2017\/11\/golodomor_samsun2-800x688.jpg"},"full":{"file":"golodomor_samsun2.jpg","width":960,"height":825,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ukr-ayna.com\/wp-content\/uploads\/2017\/11\/golodomor_samsun2.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":7081,"source_url":"https:\/\/www.ukr-ayna.com\/wp-content\/uploads\/2017\/11\/golodomor_samsun2.jpg","_links":{"self":[{"href":"https:\/\/www.ukr-ayna.com\/uk\/wp-json\/wp\/v2\/media\/7102","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ukr-ayna.com\/uk\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.ukr-ayna.com\/uk\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.ukr-ayna.com\/uk\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ukr-ayna.com\/uk\/wp-json\/wp\/v2\/comments?post=7102"}]}}